{"id":6881,"date":"2024-07-24T14:21:44","date_gmt":"2024-07-24T14:21:44","guid":{"rendered":"https:\/\/conmedicgroupe.com\/v1\/?p=6881"},"modified":"2025-06-14T10:44:36","modified_gmt":"2025-06-14T10:44:36","slug":"essaouira-signature-de-six-mou-pour-plus-de-11-mmdh-dinvestissements","status":"publish","type":"post","link":"https:\/\/conmedicgroupe.com\/v1\/2024\/07\/24\/essaouira-signature-de-six-mou-pour-plus-de-11-mmdh-dinvestissements\/","title":{"rendered":"Essaouira : Signature de six MoU pour plus de 1,1 MMDH d\u2019investissements"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Portant sur divers secteurs, particuli\u00e8rement l\u2019industrie pharmaceutique et automobile, ces m\u00e9morandums d\u2019entente visent \u00e0 stimuler le d\u00e9veloppement \u00e9conomique de la province, cr\u00e9er de nouveaux emplois et \u00e0 renforcer l\u2019attractivit\u00e9 d\u2019Essaouira en tant que destination d\u2019investissement strat\u00e9gique.<br><br>Ces m\u00e9morandums d\u2019entente ont \u00e9t\u00e9 paraph\u00e9s par le Conseiller de Sa Majest\u00e9 le Roi et pr\u00e9sident de la Fondation de Recherche, de D\u00e9veloppement et d\u2019Innovation en Sciences et Ing\u00e9nierie (FRDISI), Andr\u00e9 Azoulay, le ministre de la Sant\u00e9 et de la Protection sociale, Khalid Ait Taleb, le ministre d\u00e9l\u00e9gu\u00e9 aupr\u00e8s du Chef du gouvernement, charg\u00e9 de l\u2019Investissement, de la Convergence et de l\u2019\u00c9valuation des politiques publiques, Mohcine Jazouli, le secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de l\u2019Industrie et du Commerce, Taoufik Moucharaf, et les repr\u00e9sentants des soci\u00e9t\u00e9s concern\u00e9es.<br><br>Ainsi, le premier MoU porte sur la cr\u00e9ation d\u2019une unit\u00e9 de fabrication d\u2019\u00e9quipements et de dispositifs m\u00e9dicaux par CONMEDIC Group, avec un investissement de 314 millions de dirhams (MDH) et pr\u00e9voit la cr\u00e9ation de 224 emplois.<br><br>Le deuxi\u00e8me MoU concerne la Soci\u00e9t\u00e9 Mogador Pharma, qui investira 300 MDH dans la construction d\u2019une usine d\u00e9di\u00e9e \u00e0 la production de produits pharmaceutiques, de dispositifs m\u00e9dicaux et de compl\u00e9ments alimentaires, avec la pr\u00e9vision de g\u00e9n\u00e9rer 200 emplois.<br><br>Pour ce qui est du troisi\u00e8me MoU, il a \u00e9t\u00e9 sign\u00e9 avec la Soci\u00e9t\u00e9 GIGALAB, qui s\u2019engage \u00e0 investir 120 MDH pour la cr\u00e9ation d\u2019une usine de production de tests et d\u2019assemblage d\u2019\u00e9quipements de laboratoire, un projet qui devrait cr\u00e9er 185 emplois.<br><br>Le quatri\u00e8me MoU implique, quant \u00e0 lui, la soci\u00e9t\u00e9 GOLD COSMETIC SARL, qui investira 51 millions de dirhams (MDH) pour mettre en place une usine de valorisation des plantes aromatiques et m\u00e9dicinales \u00e0 usage cosm\u00e9tique, sanitaire et pharmaceutique, cr\u00e9ant ainsi 70 emplois.<br><br>S\u2019agissant du cinqui\u00e8me MoU, il a \u00e9t\u00e9 sign\u00e9 avec la soci\u00e9t\u00e9 LC2A, pour un projet int\u00e9gr\u00e9 de laboratoires d\u2019analyses de biologie m\u00e9dicale sp\u00e9cialis\u00e9e et d\u2019antidopage, avec un investissement de 300 MDH, pr\u00e9voyant la cr\u00e9ation de quelque 140 emplois.<br><br>Enfin, le sixi\u00e8me MoU a \u00e9t\u00e9 sign\u00e9 avec EMOVE VEHICULES COMPANY (eMVC), qui investira 50 MDH pour \u00e9tablir une unit\u00e9 industrielle de fabrication de v\u00e9hicules \u00e9lectriques. Ce projet devrait g\u00e9n\u00e9rer quelque 69 emplois.<br><br>\u201cEssaouira Investor Day\u201d se veut une plateforme dynamique et interactive, favorisant l\u2019\u00e9mergence de nouvelles opportunit\u00e9s d\u2019investissement et contribuant au rayonnement \u00e9conomique de la r\u00e9gion de Marrakech-Safi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portant sur divers secteurs, particuli\u00e8rement l\u2019industrie pharmaceutique et automobile, ces m\u00e9morandums d\u2019entente visent \u00e0 stimuler le d\u00e9veloppement \u00e9conomique de la province, cr\u00e9er de nouveaux emplois et \u00e0 renforcer l\u2019attractivit\u00e9 d\u2019Essaouira en tant que destination d\u2019investissement strat\u00e9gique. Ces m\u00e9morandums d\u2019entente ont \u00e9t\u00e9 paraph\u00e9s par le Conseiller de Sa Majest\u00e9 le Roi et pr\u00e9sident de la Fondation&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","th-blog blog-single has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/posts\/6881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/comments?post=6881"}],"version-history":[{"count":1,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/posts\/6881\/revisions"}],"predecessor-version":[{"id":6882,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/posts\/6881\/revisions\/6882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/media\/6872"}],"wp:attachment":[{"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/media?parent=6881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/categories?post=6881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conmedicgroupe.com\/v1\/wp-json\/wp\/v2\/tags?post=6881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}